{"id":6084,"date":"2017-02-17T01:00:00","date_gmt":"2017-02-17T00:00:00","guid":{"rendered":"https:\/\/www.fiwonline.de\/eu-kommission-leitet-vertragsverletzungsverfahren-gegen-deutschland-ein\/"},"modified":"2017-02-17T01:00:00","modified_gmt":"2017-02-17T00:00:00","slug":"eu-kommission-leitet-vertragsverletzungsverfahren-gegen-deutschland-ein","status":"publish","type":"post","link":"https:\/\/www.fiwonline.de\/en\/eu-kommission-leitet-vertragsverletzungsverfahren-gegen-deutschland-ein\/","title":{"rendered":"EU-Kommission leitet Vertragsverletzungsverfahren gegen Deutschland ein"},"content":{"rendered":"<div class=\"elementor-post\">\n                <!-- \n\n<div class=\"elementor-date\" style=\"font-size: 14px; color: #666;\">17.02.2017<\/div>\n\n --><\/p>\n<div class=\"elementor-keywords\">\n<div class=\"keywords-container\" style=\"background: linear-gradient(to bottom, #eee, #f5f5f5); box-shadow: 2px 2px 10px rgba(0, 0, 0, 0.28); padding: 1em 0em 1em 1em; margin: 1em 0 2em 0; border-radius: 1px; line-height: 1.5;\">\n<div class=\"title-h6\" style=\"font-size: 12pt; line-height: 18.75pt; font-weight: bold; text-align: left; color: #393D50;\">EU<br \/>Kommission<br \/>D<br \/>Vertragsverletzungsverfahren<br \/>9. GWB-Novelle<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-content\" style=\"font-size: 16px; line-height: 1.5;\">\n<p>Am 24. Januar 2017 hat die EU-Kommission auf der Grundlage von Art. 258 AEUV ein Vertragsverletzungsverfahren gegen Deutschland wegen der nicht fristgerechten Umsetzung <span style=\"text-decoration: underline;\">der Kartellschadensersatz-Richtlinie 2014\/104\/EU \u00fcber bestimmte Vorschriften f\u00fcr Schadensersatzklagen nach nationalem Recht wegen Zuwiderhandlungen gegen wettbewerbsrechtliche Bestimmungen der Mitgliedstaaten und der Europ\u00e4ischen Union<\/span> eingeleitet. Die Richtlinie h\u00e4tte bis zum 27. Dezember 2016 in nationales Recht umgesetzt werden m\u00fcssen.<\/p>\n<p>Art. 258 AEUV lautet:<\/p>\n<p><em>Hat nach Auffassung der Kommission ein Mitgliedstaat gegen eine Verpflichtung aus den Vertr\u00e4gen versto\u00dfen, so gibt sie eine mit Gr\u00fcnden versehene Stellungnahme hierzu ab; sie hat dem Staat zuvor Gelegenheit zur \u00c4u\u00dferung zu geben.<\/em><\/p>\n<p><em>Kommt der Staat dieser Stellungnahme innerhalb der von der Kommission gesetzten Frist nicht nach, so kann die Kommission den Gerichtshof der Europ\u00e4ischen Union anrufen<\/em><\/p>\n<p>Es handelt sich bislang nur um eine formale f\u00f6rmliche Einleitung des Verfahrens. Die Kommission hat noch keine Stellungnahme dazu abgegeben.<\/p>\n<p><em>Hintergrund: <\/em><\/p>\n<p>Am 28. September 2016 hat die Bundesregierung den Gesetzentwurf eines Neunten Gesetzes zur \u00c4nderung des Gesetzes gegen Wettbewerbsbeschr\u00e4nkungen (Regierungsentwurf zur 9. GWB-Novelle) ver\u00f6ffentlicht. Der Referentenentwurf war am 1. Juli 2016 ver\u00f6ffentlicht worden. Der Regierungsentwurf setzt unter anderem die Kartellschadensersatz-Richtlinie 2014\/104\/EU \u00fcber bestimmte Vorschriften f\u00fcr Schadensersatzklagen nach nationalem Recht wegen Zuwiderhandlungen gegen wettbewerbsrechtliche Bestimmungen der Mitgliedstaaten und der Europ\u00e4ischen Union um, die bis zum 27. Dezember 2016 in nationales Recht umgesetzt werden muss. Dieses Datum konnte nicht eingehalten werden, da die GWB-Novelle viele andere Regelungen enth\u00e4lt, die \u00fcber die blo\u00dfe Umsetzung der Kartellschadensersatz-Richtlinie hinausgehen und die teilweise streitig diskutiert werden, wie die Einf\u00fchrung einer Konzernhaftung. Auf den letzten Metern der Novelle wurde zudem noch diskutiert, ob das Bundeskartellamt k\u00fcnftig weitere Kompetenzen zur Durchsetzung von Verbraucherschutz erhalten sollte, insbesondere bei UWG-Verst\u00f6\u00dfen.<\/p>\n<p>Nach derzeitigem politischem Stand kann mit einem Inkrafttreten der Novelle im April 2017 gerechnet werden.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>EUKommissionDVertragsverletzungsverfahren9. GWB-Novelle Am 24. Januar 2017 hat die EU-Kommission auf der Grundlage von Art. 258 AEUV ein Vertragsverletzungsverfahren gegen Deutschland&#8230;<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"single-fullwidth.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"tp-datum":[],"tp-veranstaltung":[],"post_folder":[1243],"class_list":["post-6084","post","type-post","status-publish","format-standard","category-allgemein"],"acf":[],"menu_order":554,"_links":{"self":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/posts\/6084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/comments?post=6084"}],"version-history":[{"count":0,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/posts\/6084\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/media?parent=6084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/categories?post=6084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/tags?post=6084"},{"taxonomy":"tp-datum","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/tp-datum?post=6084"},{"taxonomy":"tp-veranstaltung","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/tp-veranstaltung?post=6084"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/post_folder?post=6084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}