{"id":6105,"date":"2017-12-21T01:00:00","date_gmt":"2017-12-21T00:00:00","guid":{"rendered":"https:\/\/www.fiwonline.de\/rede-von-johannes-laitenberger-accuracy-and-administrability-go-hand-in-hand\/"},"modified":"2017-12-21T01:00:00","modified_gmt":"2017-12-21T00:00:00","slug":"rede-von-johannes-laitenberger-accuracy-and-administrability-go-hand-in-hand","status":"publish","type":"post","link":"https:\/\/www.fiwonline.de\/en\/rede-von-johannes-laitenberger-accuracy-and-administrability-go-hand-in-hand\/","title":{"rendered":"Rede von Johannes Laitenberger: \u201eAccuracy and administrability go hand in hand\u201c"},"content":{"rendered":"<div class=\"elementor-post\">\n                <!-- \n\n<div class=\"elementor-date\" style=\"font-size: 14px; color: #666;\">21.12.2017<\/div>\n\n --><\/p>\n<div class=\"elementor-keywords\">\n<div class=\"keywords-container\" style=\"background: linear-gradient(to bottom, #eee, #f5f5f5); box-shadow: 2px 2px 10px rgba(0, 0, 0, 0.28); padding: 1em 0em 1em 1em; margin: 1em 0 2em 0; border-radius: 1px; line-height: 1.5;\">\n<div class=\"title-h6\" style=\"font-size: 12pt; line-height: 18.75pt; font-weight: bold; text-align: left; color: #393D50;\">EUKommission<br \/>Generaldirektor<br \/>Laitenberger<br \/>Rede<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-content\" style=\"font-size: 16px; line-height: 1.5;\">\n<p><span style=\"font-family: Times New Roman; font-size: small;\"> <\/span><\/p>\n<p style=\"margin: 0cm 0cm 0pt;\"><span style='font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>In seiner Rede vom 12. Dezember 2017 bei einer Veranstaltung von CRA in Br\u00fcssel sprach der Generaldirektor der Generaldirektion Wettbewerb Johannes Laitenberger \u00fcber den richtigen Ansatz von Wettbewerbsbeh\u00f6rden zur Durchsetzung des Wettbewerbsrechts. <\/span><\/p>\n<p style=\"margin: 0cm 0cm 0pt;\"><span style='font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><br \/><\/span><\/p>\n<p style=\"margin: 0cm 0cm 0pt;\"><span style='font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><\/p>\n<p style=\"margin: 0cm 0cm 0pt;\">\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Zun\u00e4chst f\u00fchrte Laitenberger aus, dass nach der Wirtschaftskrise nicht mehr die \u00dcberzeugung vorherrsche, dass die M\u00e4rkte, wenn sie nur auf sich selbst gestellt seien, notwendigerweise die effizientesten Ergebnisse erzielen w\u00fcrden, oder dass Vorteile f\u00fcr ein Unternehmen oder eine Branche sich automatisch als Wohlstand f\u00fcr die Wirtschaft und die Gesellschaft erweisen w\u00fcrden. Andererseits werde nach der Krise ein immer gr\u00f6\u00dferer Teil des t\u00e4glichen Lebens vom Markt bestimmt, was an den vielen digitalen Produkten und Dienstleistungen liege. Die Wettbewerbspolitik und -durchsetzung m\u00fcsse daher auch im digitalen Zeitalter die Probleme umfassend analysieren, das Risiko-Nutzen-Verh\u00e4ltnis optimieren und, wenn notwendig, entschieden handeln. Es gelte, zwischen den guten und schlechten Auswirkungen von Innovationen zu unterscheiden. Gut seien in der digitalen Welt Produktivit\u00e4tszuw\u00e4chse und bessere Informationen, schlecht beispielsweise Computerviren und \u201eClickbait\u201c. Die Kommission fordere mittlerweile eine &#8222;verantwortungsvolle Innovation\u201c, teilte Laitenberger mit, das hei\u00dft eine Innovation, die auf die Bed\u00fcrfnisse und Werte der Gesellschaft ausgerichtet sei und von Anfang an darauf abziele, rundum positive Ergebnisse zu erzielen.<\/span><\/p>\n<\/p>\n<p><\/span><\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='color: black; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Auf die Frage, ob sich das Wettbewerbsrecht anpassen und \u00e4ndern m\u00fcsse, meinte Laitenberger, <\/span><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>dass die Regeln des EU-Wettbewerbsrechts in den letzten 60 Jahren erstaunlich stabil geblieben seien; sie seien f\u00fcr eine Vielzahl von Szenarien entwickelt worden und h\u00e4tten sich als f\u00e4hig erwiesen, auf die unterschiedlichsten Sachverhalte angewandt zu werden.<\/span><\/span><\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Im Grunde gehe es bei der Durchsetzung des Wettbewerbsrechts aber um eine \u201e<span style=\"text-decoration: underline;\">Vers\u00f6hnung von Genauigkeit und Administrierbarkeit<\/span>\u201c, so Laitenberger. Eine geringere oder laxere Durchsetzung des Wettbewerbsrechts k\u00f6nne auf einigen M\u00e4rkten mit starken Netzwerkeffekten oder Lock-in-Effekten dazu f\u00fchren, dass sich einige Firmen so auf dem Markt festsetzten, dass potenzielle Marktteilnehmer nicht einmal versuchen w\u00fcrden, in den Markt einzutreten. Der Markt werde sich nicht in jedem Fall selbst korrigieren. Im Ergebnis m\u00fcsse man sich ebenso um eine zu geringe Durchsetzung (under-enforcement) wie um eine zu starke Durchsetzung (over-enforcement) des Wettbewerbsrechts sorgen.<\/span><\/span><\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Der Konflikt zwischen <span style=\"color: #222222;\">Genauigkeit (accuracy) und Administrierbarkeit (administrability) zeige sich auch darin, dass <\/span>a<span style=\"color: #222222;\">uf der einen Seite eine genaue kartellrechtliche Entscheidungsfindung so viele Informationen wie m\u00f6glich erfordere und daher zeit- und ressourcenintensiv sein m\u00fcsse; dies k\u00f6nne die Durchsetzung gef\u00e4hrden. Nach der Gegenansicht seien allgemeing\u00fcltige Regeln leichter administrierbar: Sie sparten Zeit und Ressourcen, verbesserten die Rechtssicherheit, seien aber auch fehleranf\u00e4lliger. Laitenberger pl\u00e4dierte daf\u00fcr, Genauigkeit und Administrierbarkeit miteinander in Einklang zu bringen. Er legte anhand zweier F\u00e4lle (ISU-Entscheidung und Intel) dar, dass dabei auch Vermutungen und ihre m\u00f6gliche Widerlegung eine Rolle spielen k\u00f6nnten. Vermutungen seien aber nur ein Ausgangspunkt oder eine Arbeitshypothese, bis das Gegenteil bewiesen w\u00e4re. Laitenberger f\u00fchrte weiter aus, dass die Kommission sehr darauf achte, die in einem Fall vorgelegten Beweise zu \u00fcberpr\u00fcfen, um ein objektives Ergebnis sicherzustellen. Hierbei finde die Kommission im Allgemeinen das richtige Gleichgewicht bei ihrer Entscheidungsfindung. L<span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-fareast-font-family: Calibri; mso-fareast-theme-font: minor-latin; mso-ansi-language: DE; mso-fareast-language: DE; mso-bidi-language: AR-SA; mso-bidi-font-size: 12.0pt;'>aitenberger folgerte schlie\u00dflich \u201eGenauigkeit ohne Administrierbarkeit ist bedeutungslos. Administrierbarkeit ohne Genauigkeit ist sinnlos.\u201c Diese Prinzipien seien miteinander in Einklang zu bringen. <\/span><br \/><\/span><\/span><\/span><\/span><\/p>\n<\/p>\n<p style=\"margin: 0cm 0cm 0pt;\">\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Zun\u00e4chst f\u00fchrte Laitenberger aus, dass nach der Wirtschaftskrise nicht mehr die \u00dcberzeugung vorherrsche, dass die M\u00e4rkte, wenn sie nur auf sich selbst gestellt seien, notwendigerweise die effizientesten Ergebnisse erzielen w\u00fcrden, oder dass Vorteile f\u00fcr ein Unternehmen oder eine Branche sich automatisch als Wohlstand f\u00fcr die Wirtschaft und die Gesellschaft erweisen w\u00fcrden. Andererseits werde nach der Krise ein immer gr\u00f6\u00dferer Teil des t\u00e4glichen Lebens vom Markt bestimmt, was an den vielen digitalen Produkten und Dienstleistungen liege. Die Wettbewerbspolitik und -durchsetzung m\u00fcsse daher auch im digitalen Zeitalter die Probleme umfassend analysieren, das Risiko-Nutzen-Verh\u00e4ltnis optimieren und, wenn notwendig, entschieden handeln. Es gelte, zwischen den guten und schlechten Auswirkungen von Innovationen zu unterscheiden. Gut seien in der digitalen Welt Produktivit\u00e4tszuw\u00e4chse und bessere Informationen, schlecht beispielsweise Computerviren und \u201eClickbait\u201c. Die Kommission fordere mittlerweile eine &#8222;verantwortungsvolle Innovation\u201c, teilte Laitenberger mit, das hei\u00dft eine Innovation, die auf die Bed\u00fcrfnisse und Werte der Gesellschaft ausgerichtet sei und von Anfang an darauf abziele, rundum positive Ergebnisse zu erzielen.<\/span><\/p>\n<\/p>\n<p style=\"margin: 0cm 0cm 0pt;\">\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Zun\u00e4chst f\u00fchrte Laitenberger aus, dass nach der Wirtschaftskrise nicht mehr die \u00dcberzeugung vorherrsche, dass die M\u00e4rkte, wenn sie nur auf sich selbst gestellt seien, notwendigerweise die effizientesten Ergebnisse erzielen w\u00fcrden, oder dass Vorteile f\u00fcr ein Unternehmen oder eine Branche sich automatisch als Wohlstand f\u00fcr die Wirtschaft und die Gesellschaft erweisen w\u00fcrden. Andererseits werde nach der Krise ein immer gr\u00f6\u00dferer Teil des t\u00e4glichen Lebens vom Markt bestimmt, was an den vielen digitalen Produkten und Dienstleistungen liege. Die Wettbewerbspolitik und -durchsetzung m\u00fcsse daher auch im digitalen Zeitalter die Probleme umfassend analysieren, das Risiko-Nutzen-Verh\u00e4ltnis optimieren und, wenn notwendig, entschieden handeln. Es gelte, zwischen den guten und schlechten Auswirkungen von Innovationen zu unterscheiden. Gut seien in der digitalen Welt Produktivit\u00e4tszuw\u00e4chse und bessere Informationen, schlecht beispielsweise Computerviren und \u201eClickbait\u201c. Die Kommission fordere mittlerweile eine &#8222;verantwortungsvolle Innovation\u201c, teilte Laitenberger mit, das hei\u00dft eine Innovation, die auf die Bed\u00fcrfnisse und Werte der Gesellschaft ausgerichtet sei und von Anfang an darauf abziele, rundum positive Ergebnisse zu erzielen.<\/span><\/p>\n<\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Zun\u00e4chst f\u00fchrte Laitenberger aus, dass nach der Wirtschaftskrise nicht mehr die \u00dcberzeugung vorherrsche, dass die M\u00e4rkte, wenn sie nur auf sich selbst gestellt seien, notwendigerweise die effizientesten Ergebnisse erzielen w\u00fcrden, oder dass Vorteile f\u00fcr ein Unternehmen oder eine Branche sich automatisch als Wohlstand f\u00fcr die Wirtschaft und die Gesellschaft erweisen w\u00fcrden. Andererseits werde nach der Krise ein immer gr\u00f6\u00dferer Teil des t\u00e4glichen Lebens vom Markt bestimmt, was an den vielen digitalen Produkten und Dienstleistungen liege. Die Wettbewerbspolitik und -durchsetzung m\u00fcsse daher auch im digitalen Zeitalter die Probleme umfassend analysieren, das Risiko-Nutzen-Verh\u00e4ltnis optimieren und, wenn notwendig, entschieden handeln. Es gelte, zwischen den guten und schlechten Auswirkungen von Innovationen zu unterscheiden. Gut seien in der digitalen Welt Produktivit\u00e4tszuw\u00e4chse und bessere Informationen, schlecht beispielsweise Computerviren und \u201eClickbait\u201c. Die Kommission fordere mittlerweile eine &#8222;verantwortungsvolle Innovation\u201c, teilte Laitenberger mit, das hei\u00dft eine Innovation, die auf die Bed\u00fcrfnisse und Werte der Gesellschaft ausgerichtet sei und von Anfang an darauf abziele, rundum positive Ergebnisse zu erzielen.<\/span><\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='color: black; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Auf die Frage, ob sich das Wettbewerbsrecht anpassen und \u00e4ndern m\u00fcsse, meinte Laitenberger, <\/span><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>dass die Regeln des EU-Wettbewerbsrechts in den letzten 60 Jahren erstaunlich stabil geblieben seien; sie seien f\u00fcr eine Vielzahl von Szenarien entwickelt worden und h\u00e4tten sich als f\u00e4hig erwiesen, auf die unterschiedlichsten Sachverhalte angewandt zu werden.<\/span><\/span><\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Im Grunde gehe es bei der Durchsetzung des Wettbewerbsrechts aber um eine \u201e<span style=\"text-decoration: underline;\">Vers\u00f6hnung von Genauigkeit und Administrierbarkeit<\/span>\u201c, so Laitenberger. Eine geringere oder laxere Durchsetzung des Wettbewerbsrechts k\u00f6nne auf einigen M\u00e4rkten mit starken Netzwerkeffekten oder Lock-in-Effekten dazu f\u00fchren, dass sich einige Firmen so auf dem Markt festsetzten, dass potenzielle Marktteilnehmer nicht einmal versuchen w\u00fcrden, in den Markt einzutreten. Der Markt werde sich nicht in jedem Fall selbst korrigieren. Im Ergebnis m\u00fcsse man sich ebenso um eine zu geringe Durchsetzung (under-enforcement) wie um eine zu starke Durchsetzung (over-enforcement) des Wettbewerbsrechts sorgen.<\/span><\/span><\/p>\n<p><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'><span style='font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-bidi-font-size: 12.0pt;'>Der Konflikt zwischen <span style=\"color: #222222;\">Genauigkeit (accuracy) und Administrierbarkeit (administrability) zeige sich auch darin, dass <\/span>a<span style=\"color: #222222;\">uf der einen Seite eine genaue kartellrechtliche Entscheidungsfindung so viele Informationen wie m\u00f6glich erfordere und daher zeit- und ressourcenintensiv sein m\u00fcsse; dies k\u00f6nne die Durchsetzung gef\u00e4hrden. Nach der Gegenansicht seien allgemeing\u00fcltige Regeln leichter administrierbar: Sie sparten Zeit und Ressourcen, verbesserten die Rechtssicherheit, seien aber auch fehleranf\u00e4lliger. Laitenberger pl\u00e4dierte daf\u00fcr, Genauigkeit und Administrierbarkeit miteinander in Einklang zu bringen. Er legte anhand zweier F\u00e4lle (ISU-Entscheidung und Intel) dar, dass dabei auch Vermutungen und ihre m\u00f6gliche Widerlegung eine Rolle spielen k\u00f6nnten. Vermutungen seien aber nur ein Ausgangspunkt oder eine Arbeitshypothese, bis das Gegenteil bewiesen w\u00e4re. Laitenberger f\u00fchrte weiter aus, dass die Kommission sehr darauf achte, die in einem Fall vorgelegten Beweise zu \u00fcberpr\u00fcfen, um ein objektives Ergebnis sicherzustellen. Hierbei finde die Kommission im Allgemeinen das richtige Gleichgewicht bei ihrer Entscheidungsfindung. L<span style='color: #222222; font-family: \"Arial\",sans-serif; font-size: 9.5pt; mso-fareast-font-family: Calibri; mso-fareast-theme-font: minor-latin; mso-ansi-language: DE; mso-fareast-language: DE; mso-bidi-language: AR-SA; mso-bidi-font-size: 12.0pt;'>aitenberger folgerte schlie\u00dflich \u201eGenauigkeit ohne Administrierbarkeit ist bedeutungslos. Administrierbarkeit ohne Genauigkeit ist sinnlos.\u201c Diese Prinzipien seien miteinander in Einklang zu bringen. <\/span><br \/><\/span><\/span><\/span><\/span><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>EUKommissionGeneraldirektorLaitenbergerRede In seiner Rede vom 12. Dezember 2017 bei einer Veranstaltung von CRA in Br\u00fcssel sprach der Generaldirektor der Generaldirektion&#8230;<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"single-fullwidth.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"tp-datum":[],"tp-veranstaltung":[],"post_folder":[1243],"class_list":["post-6105","post","type-post","status-publish","format-standard","category-allgemein"],"acf":[],"menu_order":510,"_links":{"self":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/posts\/6105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/comments?post=6105"}],"version-history":[{"count":0,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/posts\/6105\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/media?parent=6105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/categories?post=6105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/tags?post=6105"},{"taxonomy":"tp-datum","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/tp-datum?post=6105"},{"taxonomy":"tp-veranstaltung","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/tp-veranstaltung?post=6105"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.fiwonline.de\/en\/wp-json\/wp\/v2\/post_folder?post=6105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}